
{"id":104,"count":119,"description":"","link":"https:\/\/www.directout.eu\/de\/category\/press-releases\/","name":"Press Releases","slug":"press-releases","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Press Releases Archives - DirectOut<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.directout.eu\/de\/category\/press-releases\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Press Releases Archives - DirectOut\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.directout.eu\/de\/category\/press-releases\/\" \/>\n<meta property=\"og:site_name\" content=\"DirectOut\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.directout.eu\\\/category\\\/press-releases\\\/\",\"url\":\"https:\\\/\\\/www.directout.eu\\\/category\\\/press-releases\\\/\",\"name\":\"Press Releases Archives - DirectOut\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.directout.eu\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.directout.eu\\\/category\\\/press-releases\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.directout.eu\\\/category\\\/press-releases\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.directout.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Press Releases\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.directout.eu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.directout.eu\\\/de\\\/\",\"name\":\"DirectOut\",\"description\":\"Technologies\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.directout.eu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Press Releases Archives - DirectOut","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.directout.eu\/de\/category\/press-releases\/","og_locale":"de_DE","og_type":"article","og_title":"Press Releases Archives - DirectOut","og_url":"https:\/\/www.directout.eu\/de\/category\/press-releases\/","og_site_name":"DirectOut","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.directout.eu\/category\/press-releases\/","url":"https:\/\/www.directout.eu\/category\/press-releases\/","name":"Press Releases Archives - DirectOut","isPartOf":{"@id":"https:\/\/www.directout.eu\/de\/#website"},"breadcrumb":{"@id":"https:\/\/www.directout.eu\/category\/press-releases\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/www.directout.eu\/category\/press-releases\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.directout.eu\/"},{"@type":"ListItem","position":2,"name":"Press Releases"}]},{"@type":"WebSite","@id":"https:\/\/www.directout.eu\/de\/#website","url":"https:\/\/www.directout.eu\/de\/","name":"DirectOut","description":"Technologies","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.directout.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.directout.eu\/de\/wp-json\/wp\/v2\/categories\/104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.directout.eu\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.directout.eu\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.directout.eu\/de\/wp-json\/wp\/v2\/posts?categories=104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}